{"id":16835,"date":"2023-08-14T09:30:04","date_gmt":"2023-08-14T09:30:04","guid":{"rendered":"https:\/\/cascoo.ee\/product\/ratas-200p0p0p0n\/"},"modified":"2024-06-18T09:46:28","modified_gmt":"2024-06-18T09:46:28","slug":"ratas-200p0p0p0n","status":"publish","type":"product","link":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/","title":{"rendered":"Ratas 200P0P0P0N"},"content":{"rendered":"<p>Ratas on valmistatud pol\u00fcprop\u00fcleenist, ratta keskosa laius 59mm, liuglaager.<\/p>\n","protected":false},"excerpt":{"rendered":"[product_table id=\"1417\" skus=\"200P0P0P0N\"]\n","protected":false},"featured_media":18416,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[5590,5437,5975,5565],"product_tag":[],"class_list":["post-16835","product","type-product","status-publish","has-post-thumbnail","product_cat-kandevoime-250kg","product_cat-ratta-labimoot-200mm","product_cat-seeria-p0p0-polupropuleen-pp","product_cat-uksikrattad","pa_material-of-the-wheel-polupropuleen","pa_tread-turvis-polupropuleen-pp","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"ct_brands":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ratas 200P0P0P0N - Cascoo<\/title>\n<meta name=\"description\" content=\"200mm, ratas on valmistatud pol\u00fcprop\u00fcleenist, kandev\u00f5ime: 250kg\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ratas 200P0P0P0N - Cascoo\" \/>\n<meta property=\"og:description\" content=\"200mm, ratas on valmistatud pol\u00fcprop\u00fcleenist, kandev\u00f5ime: 250kg\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/\" \/>\n<meta property=\"og:site_name\" content=\"Cascoo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T09:46:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Eeldatav lugemisaeg\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/ratas-200p0p0p0n\\\/\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/ratas-200p0p0p0n\\\/\",\"name\":\"Ratas 200P0P0P0N - Cascoo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/ratas-200p0p0p0n\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/ratas-200p0p0p0n\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/080N0N0P0N-3.jpg\",\"datePublished\":\"2023-08-14T09:30:04+00:00\",\"dateModified\":\"2024-06-18T09:46:28+00:00\",\"description\":\"200mm, ratas on valmistatud pol\u00fcprop\u00fcleenist, kandev\u00f5ime: 250kg\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/ratas-200p0p0p0n\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/ratas-200p0p0p0n\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/ratas-200p0p0p0n\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/080N0N0P0N-3.jpg\",\"contentUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/080N0N0P0N-3.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"200P0P0P0N\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/ratas-200p0p0p0n\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Esileht\",\"item\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00f6\u00f6stuslikud rattad\",\"item\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ratas 200P0P0P0N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#website\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/\",\"name\":\"Cascoo\",\"description\":\"Industrial Wheels and castors\",\"publisher\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#organization\",\"name\":\"Cascoo\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Cascoo.png\",\"contentUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Cascoo.png\",\"width\":130,\"height\":51,\"caption\":\"Cascoo\"},\"image\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ratas 200P0P0P0N - Cascoo","description":"200mm, ratas on valmistatud pol\u00fcprop\u00fcleenist, kandev\u00f5ime: 250kg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/","og_locale":"et_EE","og_type":"article","og_title":"Ratas 200P0P0P0N - Cascoo","og_description":"200mm, ratas on valmistatud pol\u00fcprop\u00fcleenist, kandev\u00f5ime: 250kg","og_url":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/","og_site_name":"Cascoo","article_modified_time":"2024-06-18T09:46:28+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Eeldatav lugemisaeg":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/","url":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/","name":"Ratas 200P0P0P0N - Cascoo","isPartOf":{"@id":"https:\/\/cascoo.ee\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/#primaryimage"},"image":{"@id":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/#primaryimage"},"thumbnailUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-3.jpg","datePublished":"2023-08-14T09:30:04+00:00","dateModified":"2024-06-18T09:46:28+00:00","description":"200mm, ratas on valmistatud pol\u00fcprop\u00fcleenist, kandev\u00f5ime: 250kg","breadcrumb":{"@id":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/#primaryimage","url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-3.jpg","contentUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-3.jpg","width":1200,"height":1200,"caption":"200P0P0P0N"},{"@type":"BreadcrumbList","@id":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p0p0p0n\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Esileht","item":"https:\/\/cascoo.ee\/et\/pood\/"},{"@type":"ListItem","position":2,"name":"T\u00f6\u00f6stuslikud rattad","item":"https:\/\/cascoo.ee\/et\/pood\/"},{"@type":"ListItem","position":3,"name":"Ratas 200P0P0P0N"}]},{"@type":"WebSite","@id":"https:\/\/cascoo.ee\/et\/#website","url":"https:\/\/cascoo.ee\/et\/","name":"Cascoo","description":"Industrial Wheels and castors","publisher":{"@id":"https:\/\/cascoo.ee\/et\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cascoo.ee\/et\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Organization","@id":"https:\/\/cascoo.ee\/et\/#organization","name":"Cascoo","url":"https:\/\/cascoo.ee\/et\/","logo":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/cascoo.ee\/et\/#\/schema\/logo\/image\/","url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/07\/Cascoo.png","contentUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/07\/Cascoo.png","width":130,"height":51,"caption":"Cascoo"},"image":{"@id":"https:\/\/cascoo.ee\/et\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[{"id":16828,"url":"https:\/\/cascoo.ee\/et\/toode\/ratas-160p0p0p0n\/","url_meta":{"origin":16835,"position":0},"title":"Ratas 160P0P0P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"160P0P0P0N","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16881,"url":"https:\/\/cascoo.ee\/et\/toode\/ratas-100p0p0p0n\/","url_meta":{"origin":16835,"position":1},"title":"Ratas 100P0P0P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"080P0P0P0N","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/100P0P0P0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/100P0P0P0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/100P0P0P0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/100P0P0P0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/100P0P0P0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16890,"url":"https:\/\/cascoo.ee\/et\/toode\/ratas-080p0p0p0p0n\/","url_meta":{"origin":16835,"position":2},"title":"Ratas 080P0P0P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"080P0P0P0N","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/080N0N0P0N-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16011,"url":"https:\/\/cascoo.ee\/et\/toode\/ratas-050p4p4p4p0n\/","url_meta":{"origin":16835,"position":3},"title":"Ratas 050P4P4P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/050P4P4P0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/050P4P4P0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/050P4P4P0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/050P4P4P0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/050P4P4P0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15434,"url":"https:\/\/cascoo.ee\/et\/toode\/ratas-160p2g2b32a\/","url_meta":{"origin":16835,"position":4},"title":"Ratas 160P2G2B32A","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"160P2G2B32A","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/125P2G2B32E.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/125P2G2B32E.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/125P2G2B32E.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/125P2G2B32E.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/125P2G2B32E.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15438,"url":"https:\/\/cascoo.ee\/et\/toode\/ratas-200p2g2b32a\/","url_meta":{"origin":16835,"position":5},"title":"Ratas 200P2G2B32A","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"200P2G2B32A","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/125P2G2B32E.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/125P2G2B32E.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/125P2G2B32E.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/125P2G2B32E.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/125P2G2B32E.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product\/16835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/media\/18416"}],"wp:attachment":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/media?parent=16835"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_brand?post=16835"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_cat?post=16835"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_tag?post=16835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}