{"id":16072,"date":"2023-08-14T09:28:02","date_gmt":"2023-08-14T09:28:02","guid":{"rendered":"https:\/\/cascoo.ee\/product\/castor-tapa2c0075p2t2p0n\/"},"modified":"2024-06-09T08:36:12","modified_gmt":"2024-06-09T08:36:12","slug":"rattakomplekt-tapa2c0075p2t2p0n","status":"publish","type":"product","link":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/","title":{"rendered":"Rattakomplekt TAPA2C0075P2T2P0N"},"content":{"rendered":"<p>Tsingitud terasplekist kahvel koos kuullaagriga, kinnitus plaadiga, mille aukude vahe on 48\/38&#215;48\/38mm, kahvel materjali paksusega 2,00mm (kinnitus) ja 2,00mm (kahvel), ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, ratta keskkoha laius 28mm, liuglaager.<\/p>\n","protected":false},"excerpt":{"rendered":"[product_table id=\"1417\" skus=\"TAPA2C0075P2T2P0N\"]\n","protected":false},"featured_media":10304,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[5089,5192,5191,5190],"product_tag":[],"class_list":["post-16072","product","type-product","status-publish","has-post-thumbnail","product_cat-hargiga-rattad","product_cat-kandevoime-75kg","product_cat-ratta-labimoot-75mm","product_cat-tuup-p2t2","pa_castor-fastening-plaatkinnitusega","pa_material-of-the-wheel-polupropuleen","pa_tread-turvis-termoplastiline-kumm","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"ct_brands":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rattakomplekt TAPA2C0075P2T2P0N - Cascoo<\/title>\n<meta name=\"description\" content=\"75mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 75kg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rattakomplekt TAPA2C0075P2T2P0N - Cascoo\" \/>\n<meta property=\"og:description\" content=\"75mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 75kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/\" \/>\n<meta property=\"og:site_name\" content=\"Cascoo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-09T08:36:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0N.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa2c0075p2t2p0n\\\/\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa2c0075p2t2p0n\\\/\",\"name\":\"Rattakomplekt TAPA2C0075P2T2P0N - Cascoo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa2c0075p2t2p0n\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa2c0075p2t2p0n\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA2C0075P2T2P0N.jpg\",\"datePublished\":\"2023-08-14T09:28:02+00:00\",\"dateModified\":\"2024-06-09T08:36:12+00:00\",\"description\":\"75mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 75kg.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa2c0075p2t2p0n\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa2c0075p2t2p0n\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa2c0075p2t2p0n\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA2C0075P2T2P0N.jpg\",\"contentUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA2C0075P2T2P0N.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa2c0075p2t2p0n\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Esileht\",\"item\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00f6\u00f6stuslikud rattad\",\"item\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rattakomplekt TAPA2C0075P2T2P0N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#website\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/\",\"name\":\"Cascoo\",\"description\":\"Industrial Wheels and castors\",\"publisher\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#organization\",\"name\":\"Cascoo\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Cascoo.png\",\"contentUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Cascoo.png\",\"width\":130,\"height\":51,\"caption\":\"Cascoo\"},\"image\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rattakomplekt TAPA2C0075P2T2P0N - Cascoo","description":"75mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 75kg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/","og_locale":"et_EE","og_type":"article","og_title":"Rattakomplekt TAPA2C0075P2T2P0N - Cascoo","og_description":"75mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 75kg.","og_url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/","og_site_name":"Cascoo","article_modified_time":"2024-06-09T08:36:12+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0N.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/","url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/","name":"Rattakomplekt TAPA2C0075P2T2P0N - Cascoo","isPartOf":{"@id":"https:\/\/cascoo.ee\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/#primaryimage"},"image":{"@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/#primaryimage"},"thumbnailUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0N.jpg","datePublished":"2023-08-14T09:28:02+00:00","dateModified":"2024-06-09T08:36:12+00:00","description":"75mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 75kg.","breadcrumb":{"@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/#primaryimage","url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0N.jpg","contentUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0N.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa2c0075p2t2p0n\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Esileht","item":"https:\/\/cascoo.ee\/et\/pood\/"},{"@type":"ListItem","position":2,"name":"T\u00f6\u00f6stuslikud rattad","item":"https:\/\/cascoo.ee\/et\/pood\/"},{"@type":"ListItem","position":3,"name":"Rattakomplekt TAPA2C0075P2T2P0N"}]},{"@type":"WebSite","@id":"https:\/\/cascoo.ee\/et\/#website","url":"https:\/\/cascoo.ee\/et\/","name":"Cascoo","description":"Industrial Wheels and castors","publisher":{"@id":"https:\/\/cascoo.ee\/et\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cascoo.ee\/et\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Organization","@id":"https:\/\/cascoo.ee\/et\/#organization","name":"Cascoo","url":"https:\/\/cascoo.ee\/et\/","logo":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/cascoo.ee\/et\/#\/schema\/logo\/image\/","url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/07\/Cascoo.png","contentUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/07\/Cascoo.png","width":130,"height":51,"caption":"Cascoo"},"image":{"@id":"https:\/\/cascoo.ee\/et\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[{"id":15551,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa2c0075p2t2p0ne\/","url_meta":{"origin":16072,"position":0},"title":"Rattakomplekt TAPA2C0075P2T2P0NE","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"TAPA2C0075P2T2P0NE","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0NA-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0NA-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0NA-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0NA-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA2C0075P2T2P0NA-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16052,"url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-bah12c0075p2t2p0n\/","url_meta":{"origin":16072,"position":1},"title":"Rattakomplekt BAH12C0075P2T2P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2P0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2P0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2P0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2P0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2P0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16057,"url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-hsh12c0100p2t2p0n\/","url_meta":{"origin":16072,"position":2},"title":"Rattakomplekt HSH12C0100P2T2P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HSH12C0100P2T2P0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HSH12C0100P2T2P0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HSH12C0100P2T2P0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HSH12C0100P2T2P0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HSH12C0100P2T2P0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16061,"url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-bsh12c0100p2t2p0n\/","url_meta":{"origin":16072,"position":3},"title":"Rattakomplekt BSH12C0100P2T2P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BSH12C0100P2T2P0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BSH12C0100P2T2P0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BSH12C0100P2T2P0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BSH12C0100P2T2P0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BSH12C0100P2T2P0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16080,"url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-hah12c0075p2t2p0n\/","url_meta":{"origin":16072,"position":4},"title":"Rattakomplekt HAH12C0075P2T2P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HAH12C0075P2T2P0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HAH12C0075P2T2P0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HAH12C0075P2T2P0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HAH12C0075P2T2P0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HAH12C0075P2T2P0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15638,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-fbp22wc080p2w2p0n\/","url_meta":{"origin":16072,"position":5},"title":"Rattakomplekt FBP22WC080P2W2P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"FBP22WC080P2W2P0N","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FBP22WC080P2W2P0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FBP22WC080P2W2P0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FBP22WC080P2W2P0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FBP22WC080P2W2P0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FBP22WC080P2W2P0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product\/16072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/media\/10304"}],"wp:attachment":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/media?parent=16072"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_brand?post=16072"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_cat?post=16072"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_tag?post=16072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}