{"id":16063,"date":"2023-08-14T09:28:02","date_gmt":"2023-08-14T09:28:02","guid":{"rendered":"https:\/\/cascoo.ee\/product\/toostusratas-tapa9c0050p2t2b42\/"},"modified":"2024-10-23T08:21:40","modified_gmt":"2024-10-23T08:21:40","slug":"rattakomplekt-tapa9c0050p2t2b42","status":"publish","type":"product","link":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/","title":{"rendered":"Rattakomplekt TAPA9C0050P2T2B42"},"content":{"rendered":"<p>Tsingitud terasplekist kahvel koos kuullaagriga, kinnitus plaadiga, mille aukude vahe on 48\/39&#215;48\/39mm, kahvel materjali paksusega 2,00mm (kinnitus) ja 1,80mm (kahvel), ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, ratta keskosa laius 22mm, kuullaager, t\u00e4ielikult kattev plastikust laagrikaitse.<\/p>\n","protected":false},"excerpt":{"rendered":"[product_table id=\"1417\" skus=\"TAPA9C0050P2T2B42\"]\n","protected":false},"featured_media":10296,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[5089,5762,5761,5190],"product_tag":[],"class_list":["post-16063","product","type-product","status-publish","has-post-thumbnail","product_cat-hargiga-rattad","product_cat-kandevoime-50kg","product_cat-ratta-diameeter-50mm","product_cat-tuup-p2t2","pa_castor-fastening-plaatkinnitusega","pa_material-of-the-wheel-polupropuleen","pa_tread-turvis-termoplastiline-kumm","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"ct_brands":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rattakomplekt TAPA9C0050P2T2B42 - Cascoo<\/title>\n<meta name=\"description\" content=\"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 50kg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rattakomplekt TAPA9C0050P2T2B42 - Cascoo\" \/>\n<meta property=\"og:description\" content=\"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 50kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/\" \/>\n<meta property=\"og:site_name\" content=\"Cascoo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T08:21:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Eeldatav lugemisaeg\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa9c0050p2t2b42\\\/\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa9c0050p2t2b42\\\/\",\"name\":\"Rattakomplekt TAPA9C0050P2T2B42 - Cascoo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa9c0050p2t2b42\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa9c0050p2t2b42\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA9C0050P2T2B42.jpg\",\"datePublished\":\"2023-08-14T09:28:02+00:00\",\"dateModified\":\"2024-10-23T08:21:40+00:00\",\"description\":\"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 50kg.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa9c0050p2t2b42\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa9c0050p2t2b42\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa9c0050p2t2b42\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA9C0050P2T2B42.jpg\",\"contentUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA9C0050P2T2B42.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/rattakomplekt-tapa9c0050p2t2b42\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Esileht\",\"item\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00f6\u00f6stuslikud rattad\",\"item\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rattakomplekt TAPA9C0050P2T2B42\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#website\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/\",\"name\":\"Cascoo\",\"description\":\"Industrial Wheels and castors\",\"publisher\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#organization\",\"name\":\"Cascoo\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Cascoo.png\",\"contentUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Cascoo.png\",\"width\":130,\"height\":51,\"caption\":\"Cascoo\"},\"image\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rattakomplekt TAPA9C0050P2T2B42 - Cascoo","description":"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 50kg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/","og_locale":"et_EE","og_type":"article","og_title":"Rattakomplekt TAPA9C0050P2T2B42 - Cascoo","og_description":"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 50kg.","og_url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/","og_site_name":"Cascoo","article_modified_time":"2024-10-23T08:21:40+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Eeldatav lugemisaeg":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/","url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/","name":"Rattakomplekt TAPA9C0050P2T2B42 - Cascoo","isPartOf":{"@id":"https:\/\/cascoo.ee\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/#primaryimage"},"image":{"@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/#primaryimage"},"thumbnailUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg","datePublished":"2023-08-14T09:28:02+00:00","dateModified":"2024-10-23T08:21:40+00:00","description":"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, turvis termoplastilisest kummist 95\u00b0 Shore A, kandev\u00f5ime: 50kg.","breadcrumb":{"@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/#primaryimage","url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg","contentUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-tapa9c0050p2t2b42\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Esileht","item":"https:\/\/cascoo.ee\/et\/pood\/"},{"@type":"ListItem","position":2,"name":"T\u00f6\u00f6stuslikud rattad","item":"https:\/\/cascoo.ee\/et\/pood\/"},{"@type":"ListItem","position":3,"name":"Rattakomplekt TAPA9C0050P2T2B42"}]},{"@type":"WebSite","@id":"https:\/\/cascoo.ee\/et\/#website","url":"https:\/\/cascoo.ee\/et\/","name":"Cascoo","description":"Industrial Wheels and castors","publisher":{"@id":"https:\/\/cascoo.ee\/et\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cascoo.ee\/et\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Organization","@id":"https:\/\/cascoo.ee\/et\/#organization","name":"Cascoo","url":"https:\/\/cascoo.ee\/et\/","logo":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/cascoo.ee\/et\/#\/schema\/logo\/image\/","url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/07\/Cascoo.png","contentUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/07\/Cascoo.png","width":130,"height":51,"caption":"Cascoo"},"image":{"@id":"https:\/\/cascoo.ee\/et\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[{"id":15541,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2b42e\/","url_meta":{"origin":16063,"position":0},"title":"Rattakomplekt TAPA9C0050P2T2B42E","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"TAPA9C0050P2T2P0NE","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13047,"url":"https:\/\/cascoo.ee\/product\/castor-tapa9c0050p2t2b42\/","url_meta":{"origin":16063,"position":1},"title":"Castor TAPA9C0050P2T2B42","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":20460,"url":"https:\/\/cascoo.ee\/fi\/tuote\/kaantopyora-tapa9c0050p2t2b42\/","url_meta":{"origin":16063,"position":2},"title":"Py\u00f6r\u00e4 TAPA9C0050P2T2B42","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14489,"url":"https:\/\/cascoo.ee\/product\/castor-tapa9c0050p2t2b42e\/","url_meta":{"origin":16063,"position":3},"title":"Castor TAPA9C0050P2T2B42E","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"TAPA9C0050P2T2P0NE","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2B42E.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15295,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-fep05w0100p2a2p0n\/","url_meta":{"origin":16063,"position":4},"title":"Rattakomplekt FEP05W0100P2A2P0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"FEP05W0100P2A2P0N","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FEP05W0100P2A2P0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FEP05W0100P2A2P0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FEP05W0100P2A2P0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FEP05W0100P2A2P0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FEP05W0100P2A2P0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16088,"url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-fhp5mwc200z0z0d0n\/","url_meta":{"origin":16063,"position":5},"title":"Rattakomplekt FHP5MWC200Z0Z0D0N","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FHP5MWC200Z0Z0D0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FHP5MWC200Z0Z0D0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FHP5MWC200Z0Z0D0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FHP5MWC200Z0Z0D0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/FHP5MWC200Z0Z0D0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product\/16063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/media\/10296"}],"wp:attachment":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/media?parent=16063"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_brand?post=16063"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_cat?post=16063"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_tag?post=16063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}