{"id":15552,"date":"2023-08-14T09:41:17","date_gmt":"2023-08-14T09:41:17","guid":{"rendered":"https:\/\/cascoo.ee\/product\/castor-tapa9c0050p2t2p0na\/"},"modified":"2024-06-11T12:22:21","modified_gmt":"2024-06-11T12:22:21","slug":"castor-tapa9c0050p2t2p0na","status":"publish","type":"product","link":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/","title":{"rendered":"Rattakomplekt TAPA9C0050P2T2P0NA"},"content":{"rendered":"<p>Tsingitud terasplekist kahvel koos kuullaagriga, kinnitus plaadiga, mille aukude vahe 48\/39&#215;48\/39mm, kahvel materjali paksusega 2,00mm (kinnitus) ja 1,80mm (kahvel), ratta sisemine osa pol\u00fcprop\u00fcleenist, antistaatiline ja turvis termoplastilisest kummist 95\u00b0 Shore A, antistaatiline, ratta keskosa laius 22mm, liugelaager.<\/p>\n","protected":false},"excerpt":{"rendered":"[product_table id=\"1417\" skus=\"TAPA9C0050P2T2P0NA\"]\n","protected":false},"featured_media":18265,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[5089,6150,5761,6188],"product_tag":[],"class_list":["post-15552","product","type-product","status-publish","has-post-thumbnail","product_cat-hargiga-rattad","product_cat-kandevoime-30kg","product_cat-ratta-diameeter-50mm","product_cat-seeria-p2t2-antistaatiline","pa_castor-fastening-plaatkinnitusega","pa_material-of-the-wheel-polupropuleen","pa_tread-turvis-termoplastiline-kumm","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"ct_brands":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rattakomplekt TAPA9C0050P2T2P0NA - Cascoo<\/title>\n<meta name=\"description\" content=\"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, antistaatiline, turvis termoplastilisest kummist 95\u00b0 Shore A, antistaatiline, kandev\u00f5ime: 30kg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rattakomplekt TAPA9C0050P2T2P0NA - Cascoo\" \/>\n<meta property=\"og:description\" content=\"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, antistaatiline, turvis termoplastilisest kummist 95\u00b0 Shore A, antistaatiline, kandev\u00f5ime: 30kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/\" \/>\n<meta property=\"og:site_name\" content=\"Cascoo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T12:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2P0NA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Eeldatav lugemisaeg\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/castor-tapa9c0050p2t2p0na\\\/\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/castor-tapa9c0050p2t2p0na\\\/\",\"name\":\"Rattakomplekt TAPA9C0050P2T2P0NA - Cascoo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/castor-tapa9c0050p2t2p0na\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/castor-tapa9c0050p2t2p0na\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA9C0050P2T2P0NA.jpg\",\"datePublished\":\"2023-08-14T09:41:17+00:00\",\"dateModified\":\"2024-06-11T12:22:21+00:00\",\"description\":\"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, antistaatiline, turvis termoplastilisest kummist 95\u00b0 Shore A, antistaatiline, kandev\u00f5ime: 30kg.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/castor-tapa9c0050p2t2p0na\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/castor-tapa9c0050p2t2p0na\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/castor-tapa9c0050p2t2p0na\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA9C0050P2T2P0NA.jpg\",\"contentUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TAPA9C0050P2T2P0NA.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"TAPA9C0050P2T2P0NA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/toode\\\/castor-tapa9c0050p2t2p0na\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Esileht\",\"item\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00f6\u00f6stuslikud rattad\",\"item\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rattakomplekt TAPA9C0050P2T2P0NA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#website\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/\",\"name\":\"Cascoo\",\"description\":\"Industrial Wheels and castors\",\"publisher\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#organization\",\"name\":\"Cascoo\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Cascoo.png\",\"contentUrl\":\"https:\\\/\\\/cascoo.ee\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Cascoo.png\",\"width\":130,\"height\":51,\"caption\":\"Cascoo\"},\"image\":{\"@id\":\"https:\\\/\\\/cascoo.ee\\\/et\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rattakomplekt TAPA9C0050P2T2P0NA - Cascoo","description":"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, antistaatiline, turvis termoplastilisest kummist 95\u00b0 Shore A, antistaatiline, kandev\u00f5ime: 30kg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/","og_locale":"et_EE","og_type":"article","og_title":"Rattakomplekt TAPA9C0050P2T2P0NA - Cascoo","og_description":"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, antistaatiline, turvis termoplastilisest kummist 95\u00b0 Shore A, antistaatiline, kandev\u00f5ime: 30kg.","og_url":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/","og_site_name":"Cascoo","article_modified_time":"2024-06-11T12:22:21+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2P0NA.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Eeldatav lugemisaeg":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/","url":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/","name":"Rattakomplekt TAPA9C0050P2T2P0NA - Cascoo","isPartOf":{"@id":"https:\/\/cascoo.ee\/et\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/#primaryimage"},"image":{"@id":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/#primaryimage"},"thumbnailUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2P0NA.jpg","datePublished":"2023-08-14T09:41:17+00:00","dateModified":"2024-06-11T12:22:21+00:00","description":"50mm, rattakomplekt, piduriga, ratta sisemine osa pol\u00fcprop\u00fcleenist, antistaatiline, turvis termoplastilisest kummist 95\u00b0 Shore A, antistaatiline, kandev\u00f5ime: 30kg.","breadcrumb":{"@id":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/#primaryimage","url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2P0NA.jpg","contentUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/08\/TAPA9C0050P2T2P0NA.jpg","width":1200,"height":1200,"caption":"TAPA9C0050P2T2P0NA"},{"@type":"BreadcrumbList","@id":"https:\/\/cascoo.ee\/et\/toode\/castor-tapa9c0050p2t2p0na\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Esileht","item":"https:\/\/cascoo.ee\/et\/pood\/"},{"@type":"ListItem","position":2,"name":"T\u00f6\u00f6stuslikud rattad","item":"https:\/\/cascoo.ee\/et\/pood\/"},{"@type":"ListItem","position":3,"name":"Rattakomplekt TAPA9C0050P2T2P0NA"}]},{"@type":"WebSite","@id":"https:\/\/cascoo.ee\/et\/#website","url":"https:\/\/cascoo.ee\/et\/","name":"Cascoo","description":"Industrial Wheels and castors","publisher":{"@id":"https:\/\/cascoo.ee\/et\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cascoo.ee\/et\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Organization","@id":"https:\/\/cascoo.ee\/et\/#organization","name":"Cascoo","url":"https:\/\/cascoo.ee\/et\/","logo":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/cascoo.ee\/et\/#\/schema\/logo\/image\/","url":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/07\/Cascoo.png","contentUrl":"https:\/\/cascoo.ee\/wp-content\/uploads\/2023\/07\/Cascoo.png","width":130,"height":51,"caption":"Cascoo"},"image":{"@id":"https:\/\/cascoo.ee\/et\/#\/schema\/logo\/image\/"}}]}},"jetpack-related-posts":[{"id":15335,"url":"https:\/\/cascoo.ee\/et\/toode\/rattakomplekt-bah12c0075p2t2b42a\/","url_meta":{"origin":15552,"position":0},"title":"Rattakomplekt BAH12C0075P2T2B42A","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"BAH12C0075P2T2B42E","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2B42E-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2B42E-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2B42E-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2B42E-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BAH12C0075P2T2B42E-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15346,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-bph98wc200p4s4r0na\/","url_meta":{"origin":15552,"position":1},"title":"Rattakomplekt BPH98WC200P4S4R0NA","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"BBH85WC125P4S4R0NA","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15361,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-bph98wc160p4s4r0na\/","url_meta":{"origin":15552,"position":2},"title":"Rattakomplekt BPH98WC160P4S4R0NA","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"BBH85WC125P4S4R0NA","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/07\/BBH85WC125P4S4R0N.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15362,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-bbh35wc080p4s4r0na\/","url_meta":{"origin":15552,"position":3},"title":"Rattakomplekt BBH35WC080P4S4R0NA","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"BPH97WC250P4S4R0N","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BPH98WC200P4S4R0NE.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BPH98WC200P4S4R0NE.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BPH98WC200P4S4R0NE.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15364,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-hph98wc160p4s4r0na\/","url_meta":{"origin":15552,"position":4},"title":"Rattakomplekt HPH98WC160P4S4R0NA","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"HPH98WC160P4S4R0NA","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HPH98WC200P4S4R0NE-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HPH98WC200P4S4R0NE-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/HPH98WC200P4S4R0NE-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15366,"url":"https:\/\/cascoo.ee\/et\/toode\/castor-bbh35wc100p4s4r0na\/","url_meta":{"origin":15552,"position":5},"title":"Rattakomplekt BBH35WC100P4S4R0NA","author":"admin","date":"14. aug 2023","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"BBH35WC100P4S4R0NA","src":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BBH35WC100P4S4R0N.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BBH35WC100P4S4R0N.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BBH35WC100P4S4R0N.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cascoo.ee\/wp-content\/uploads\/2023\/08\/BBH35WC100P4S4R0N.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product\/15552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/media\/18265"}],"wp:attachment":[{"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/media?parent=15552"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_brand?post=15552"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_cat?post=15552"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cascoo.ee\/et\/wp-json\/wp\/v2\/product_tag?post=15552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}